{"id":36276,"date":"2021-11-23T13:06:13","date_gmt":"2021-11-23T16:06:13","guid":{"rendered":"http:\/\/www.almargenweb.com.ar\/web\/?p=36276"},"modified":"2021-11-23T13:06:15","modified_gmt":"2021-11-23T16:06:15","slug":"sueno-con-la-casa-propia-construir-una-vivienda-de-70m2-cuesta-45-millones-de-pesos","status":"publish","type":"post","link":"https:\/\/www.almargenweb.com.ar\/web\/sueno-con-la-casa-propia-construir-una-vivienda-de-70m2-cuesta-45-millones-de-pesos\/","title":{"rendered":"Sue\u00f1o con la casa propia; construir una vivienda de 70m2 cuesta 4,5 millones de pesos"},"content":{"rendered":"\n<p>Cada a\u00f1o que pasa, el sue\u00f1o de la casa propia se uelve inalcanzable para los millones de argentinos con deficit habitacional.<\/p>\n\n\n\n<p>Seg\u00fan un revelamiento en corralones y venta de materiales para la construcci\u00f3n, construir una vivienda de 70 metros cuadrados, que en octubre de 2020 costaba 2.740.002 de pesos, en el mismo mes de este a\u00f1o costo $4.513.016.<\/p>\n\n\n\n<p>Esta cifra deja en evidencia el proceso inflacionario que atraviesa el pa\u00eds, sumado sumado a una feroz perdida del valor monetario, de la moneda nacional, respecto al dolar.<\/p>\n\n\n\n<p>Los datos dados a conocer por el Instituto Provincial de Estad\u00edsticas y censos, la construcci\u00f3n sufri\u00f3 una variaci\u00f3n porcentual del 64.7%, respecto al a\u00f1o anterior. Es decir, que en junio del 2021, el metro cuadrado de construcci\u00f3n costo $4.513.016.<\/p>\n\n\n\n<p>El costo sufri\u00f3 una suba del 4,4% en relaci\u00f3n al mes anterior. Este resultado surge como consecuencia del alza de 2,6% de los materiales, de 5,5% de la mano de obra, sumado al 15% en el sector de &#8220;gastos generales&#8221;.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o que pasa, el sue\u00f1o de la casa propia se uelve inalcanzable para los millones [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":36278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2,164,5,140],"tags":[],"class_list":["post-36276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ambiente","category-economia","category-nacionales"],"_links":{"self":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/36276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=36276"}],"version-history":[{"count":1,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/36276\/revisions"}],"predecessor-version":[{"id":36279,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/36276\/revisions\/36279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media\/36278"}],"wp:attachment":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=36276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=36276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=36276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}