{"id":34575,"date":"2021-04-17T10:18:47","date_gmt":"2021-04-17T13:18:47","guid":{"rendered":"http:\/\/www.almargenweb.com.ar\/web\/?p=34575"},"modified":"2021-04-17T10:18:48","modified_gmt":"2021-04-17T13:18:48","slug":"economias-regionales-mejora-la-exportacion-de-carne-de-cerdo","status":"publish","type":"post","link":"https:\/\/www.almargenweb.com.ar\/web\/economias-regionales-mejora-la-exportacion-de-carne-de-cerdo\/","title":{"rendered":"Econom\u00edas regionales; mejora la exportaci\u00f3n de carne de cerdo"},"content":{"rendered":"\n<p>El gerente general del Consorcio de Exportaci\u00f3n de Carne de Cerdo Argenpork, Guillermo Proietto sostuvo que &#8220;la actividad puede seguir creciendo, aunque existen limitaciones en cuestiones de infraestructura que pueden condicionar el aumento de exportaciones&#8221;.<\/p>\n\n\n\n<p>Con respecto a la pandemia, el empresario dijo que &#8220;lo m\u00e1s dif\u00edcil se vivi\u00f3 el a\u00f1o pasado cuando realmente se ve\u00edan problemas operativos en las plantas de faena y desposte&#8221; y a\u00f1adi\u00f3 que &#8220;en la industria no hay contagios masivos&#8221;.<\/p>\n\n\n\n<p>Los \u00faltimos datos de exportaciones marcan crecimientos interanuales muy marcados en los primeros meses del a\u00f1o, por encima del 70%.<\/p>\n\n\n\n<p>En cuanto a las expectativas para 2021, Proietto estim\u00f3 que el crecimiento va a seguir. &#8220;No creo que a las tasas de crecimiento que se ven\u00edan dando se mantengan, porque nos encontramos con limitaciones de infraestructura porque Argentina no estaba preparada para este aumento&#8221;, precis\u00f3.<\/p>\n\n\n\n<p>Con respecto a la exportaci\u00f3n, consider\u00f3 que &#8220;va a estar rondando las 45.000 o 50.000 toneladas de carne porcina contra las 40.000 o 42.000 toneladas del a\u00f1o pasado&#8221;.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El gerente general del Consorcio de Exportaci\u00f3n de Carne de Cerdo Argenpork, Guillermo Proietto sostuvo que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":34577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2,5],"tags":[],"class_list":["post-34575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-economia"],"_links":{"self":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/34575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=34575"}],"version-history":[{"count":1,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/34575\/revisions"}],"predecessor-version":[{"id":34578,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/34575\/revisions\/34578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media\/34577"}],"wp:attachment":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=34575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=34575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=34575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}