{"id":32716,"date":"2021-01-12T17:29:23","date_gmt":"2021-01-12T20:29:23","guid":{"rendered":"http:\/\/www.almargenweb.com.ar\/web\/?p=32716"},"modified":"2021-01-12T17:29:23","modified_gmt":"2021-01-12T20:29:23","slug":"rige-un-nuevo-aumento-del-combustible-en-santa-fe","status":"publish","type":"post","link":"https:\/\/www.almargenweb.com.ar\/web\/rige-un-nuevo-aumento-del-combustible-en-santa-fe\/","title":{"rendered":"Rige un nuevo aumento del combustible en Santa Fe"},"content":{"rendered":"\n<p>Los expendedores de nafta y de gasoil abrieron la jornada con una suba del uno por ciento en toda la provincia, mientras que, desde la C\u00e1mara de Combustibles, no descartaron que el 15 de enero pueda darse una nueva alza.<\/p>\n\n\n\n<p>En lo que va del 2021, las petroleras YPF, Raizen -que opera la marca Shell- y Axion concretaron &#8220;actualizaciones&#8221; en los precios de combustibles en el orden del cuatro por ciento, al trasladar a los surtidores los nuevos valores reconocidos por el Gobierno a los biocombustibles, como el biodiesel y el bioetanol que se utilizan para las mezclas obligatorias.<\/p>\n\n\n\n<p>En similares circunstancias, la nueva readecuaci\u00f3n de precios que termin\u00f3 materializ\u00e1ndose este martes, se debi\u00f3 a un reajuste impositivo como resultado de la variaci\u00f3n trimestral de la inflaci\u00f3n, pero tambi\u00e9n, a causa de las actualizaciones del biocombustible que se utilizan para las mezclas obligatorias.<\/p>\n\n\n\n<p>En consecuencia, los precios de referencia quedaron fijados para la S\u00faper en $75,60, para Infinia en $86,20, para Infinia Diesel en $79,30 y Diesel 500 en $67,20.<\/p>\n\n\n\n<p>En rigor, el \u00faltimo aumento autorizado por el Gobierno se registr\u00f3 el pasado 15 de diciembre como actualizaci\u00f3n del segundo trimestre del 2020, mientras que, a mediados de este mes, est\u00e1 previsto que se actualice el del tercer trimestre del a\u00f1o pasado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los expendedores de nafta y de gasoil abrieron la jornada con una suba del uno por [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":32718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2,5,48],"tags":[],"class_list":["post-32716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-economia","category-provinciales"],"_links":{"self":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/32716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=32716"}],"version-history":[{"count":1,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/32716\/revisions"}],"predecessor-version":[{"id":32719,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/32716\/revisions\/32719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media\/32718"}],"wp:attachment":[{"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=32716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=32716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.almargenweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=32716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}